{"id":638,"date":"2016-09-28T15:15:09","date_gmt":"2016-09-28T19:15:09","guid":{"rendered":"http:\/\/dev2.mtccc.com\/fr\/?page_id=638"},"modified":"2023-08-21T13:36:47","modified_gmt":"2023-08-21T17:36:47","slug":"the-leaders-circle","status":"publish","type":"page","link":"https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/","title":{"rendered":"Cercle des Leaders"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_empty_space][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/12&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_column_text]Le programme du Cercle des Leaders s\u2019associe aux principaux penseurs, innovateurs et chercheurs pour organiser la tenue de rencontres multinationales \u00e0 Toronto. Gr\u00e2ce \u00e0 l\u2019expertise combin\u00e9e de ses membres, le Cercle des Leaders s\u2019assure que la m\u00e9tropole continue d\u2019accueillir ces conf\u00e9rences internationales d\u2019envergure qui facilitent le transfert de connaissances, s\u2019appuient sur la r\u00e9putation mondiale de la ville, favorisent l\u2019innovation et les institutions novatrices, en plus de produire d\u2019importantes retomb\u00e9es socio\u00e9conomiques pour la grande r\u00e9gion de Toronto. Pour en savoir plus sur ce programme, visitez <a href=\"http:\/\/theleaderscircle.ca\/\" target=\"_blank\" rel=\"noopener\">theleaderscircle.ca<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Le Cercle des Leaders b\u00e9n\u00e9ficie de l\u2019appui du Palais des congr\u00e8s du Toronto m\u00e9tropolitain.<\/p>\n<p>&nbsp;<\/p>\n<p><a class=\"acf-btn acf-btn-outline\" href=\"http:\/\/theleaderscircle.ca\/\" target=\"_blank\" rel=\"noopener\">EN SAVOIR PLUS<\/a>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/12&Prime;][\/vc_column][vc_column width=\u00a0\u00bb5\/12&Prime;][vc_single_image image=\u00a0\u00bb332829&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/12&Prime;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/3&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb20560&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbright\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_column_text el_class=\u00a0\u00bbttl-text-align\u00a0\u00bb][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_empty_space][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/12&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_column_text]Le programme du Cercle des Leaders s\u2019associe aux principaux penseurs, innovateurs et chercheurs pour organiser la tenue de rencontres multinationales \u00e0 Toronto. Gr\u00e2ce \u00e0 l\u2019expertise combin\u00e9e de ses membres, le Cercle des Leaders s\u2019assure que la m\u00e9tropole continue d\u2019accueillir ces conf\u00e9rences internationales d\u2019envergure qui facilitent le transfert [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":331759,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"template-new-default.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-638","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cercle des Leaders - Metro Toronto Convention Centre<\/title>\n<meta name=\"description\" content=\"Find information regarding the MTCC\u2019s exclusive program, The Leaders Circle, here.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cercle des Leaders - Metro Toronto Convention Centre\" \/>\n<meta property=\"og:description\" content=\"Find information regarding the MTCC\u2019s exclusive program, The Leaders Circle, here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/\" \/>\n<meta property=\"og:site_name\" content=\"Metro Toronto Convention Centre\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-21T17:36:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/the-leaders-circle\\\/\",\"url\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/the-leaders-circle\\\/\",\"name\":\"Cercle des Leaders - Metro Toronto Convention Centre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/#website\"},\"datePublished\":\"2016-09-28T19:15:09+00:00\",\"dateModified\":\"2023-08-21T17:36:47+00:00\",\"description\":\"Find information regarding the MTCC\u2019s exclusive program, The Leaders Circle, here.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/the-leaders-circle\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/the-leaders-circle\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/the-leaders-circle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entreprise\",\"item\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cercle des Leaders\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/\",\"name\":\"Metro Toronto Convention Centre\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cercle des Leaders - Metro Toronto Convention Centre","description":"Find information regarding the MTCC\u2019s exclusive program, The Leaders Circle, here.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/","og_locale":"fr_CA","og_type":"article","og_title":"Cercle des Leaders - Metro Toronto Convention Centre","og_description":"Find information regarding the MTCC\u2019s exclusive program, The Leaders Circle, here.","og_url":"https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/","og_site_name":"Metro Toronto Convention Centre","article_modified_time":"2023-08-21T17:36:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/","url":"https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/","name":"Cercle des Leaders - Metro Toronto Convention Centre","isPartOf":{"@id":"https:\/\/dev2.mtccc.com\/fr\/#website"},"datePublished":"2016-09-28T19:15:09+00:00","dateModified":"2023-08-21T17:36:47+00:00","description":"Find information regarding the MTCC\u2019s exclusive program, The Leaders Circle, here.","breadcrumb":{"@id":"https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev2.mtccc.com\/fr\/corporate\/the-leaders-circle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev2.mtccc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Entreprise","item":"https:\/\/dev2.mtccc.com\/fr\/corporate\/"},{"@type":"ListItem","position":3,"name":"Cercle des Leaders"}]},{"@type":"WebSite","@id":"https:\/\/dev2.mtccc.com\/fr\/#website","url":"https:\/\/dev2.mtccc.com\/fr\/","name":"Metro Toronto Convention Centre","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev2.mtccc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages\/638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/comments?post=638"}],"version-history":[{"count":22,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages\/638\/revisions"}],"predecessor-version":[{"id":333007,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages\/638\/revisions\/333007"}],"up":[{"embeddable":true,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages\/331759"}],"wp:attachment":[{"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/media?parent=638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}