{"id":10131,"date":"2016-11-03T12:03:15","date_gmt":"2016-11-03T16:03:15","guid":{"rendered":"http:\/\/dev2.mtccc.com\/fr\/?page_id=10131"},"modified":"2022-08-25T14:59:03","modified_gmt":"2022-08-25T18:59:03","slug":"open-government","status":"publish","type":"page","link":"https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/","title":{"rendered":"Gouvernement ouvert"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row disable_element=\u00a0\u00bbyes\u00a0\u00bb][vc_column][vc_column_text]La cr\u00e9ation du Palais des congr\u00e8s du Toronto m\u00e9tropolitain est le fruit d\u2019un travail collectif entre le gouvernement f\u00e9d\u00e9ral du Canada, la province de l\u2019Ontario et la municipalit\u00e9 de la r\u00e9gion m\u00e9tropolitaine de Toronto. Le MTCC est conforme aux exigences du gouvernement et est tenu pleinement responsable du strict respect de celles-ci.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<\/p>\n<h2>Donn\u00e9es ouvertes<\/h2>\n<form id=\"aspnetForm\" action=\"http:\/\/dev.mtccc.com\/corporate\/memorandumOfUnderstanding.aspx\" method=\"post\" name=\"aspnetForm\">\n<div id=\"ctl00_ctl00_baseContent_rightColContent_contnetControl_cmsContent\">\n<p>Consultez notre liste de r\u00e9pertoire des donn\u00e9es ouvertes en cliquant sur le lien ci-dessous\u00a0:<\/p>\n<p><a class=\"acf-btn acf-btn-outline acf-header-btn pink-text\" href=\"\/wp-content\/uploads\/2016\/10\/Open_Dataset_Inventory.pdf\" target=\"_blank\">Liste de r\u00e9pertoire des donn\u00e9es ouvertes<\/a><\/p>\n<\/div>\n<\/form>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<\/p>\n<h2>Protocole d\u2019entente<\/h2>\n<form id=\"aspnetForm\" action=\"http:\/\/dev.mtccc.com\/corporate\/memorandumOfUnderstanding.aspx\" method=\"post\" name=\"aspnetForm\">\n<div id=\"ctl00_ctl00_baseContent_rightColContent_contnetControl_cmsContent\">\n<p>Consultez notre protocole d\u2019entente en cliquant sur le lien ci-dessous.<\/p>\n<div>\n<p><a class=\"acf-btn acf-btn-outline acf-header-btn pink-text\" href=\"\/wp-content\/uploads\/2016\/10\/MTCC_MOU_English.pdf\" target=\"_blank\">Protocole d\u2019entente<\/a><\/p>\n<\/div>\n<\/div>\n<\/form>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2><strong>Cadre de r\u00e9mun\u00e9ration des cadres sup\u00e9rieurs du secteur parapublic<\/strong><\/h2>\n<p>Le gouvernement de l\u2019Ontario instaure un nouveau cadre de r\u00e9mun\u00e9ration des cadres sup\u00e9rieurs du secteur parapublic. Le r\u00e8glement du cadre de r\u00e9mun\u00e9ration des cadres sup\u00e9rieurs du secteur parapublic est entr\u00e9 en vigueur le 6 septembre 2016. Il s\u2019applique \u00e0 tous les employeurs d\u00e9sign\u00e9s aux termes de la\u00a0<em>Loi de 2014 sur la r\u00e9mun\u00e9ration des cadres du secteur parapublic<\/em>\u00a0et \u00e9tablit les exigences que doivent respecter les employeurs d\u00e9sign\u00e9s du secteur parapublic lors de l\u2019\u00e9tablissement de leurs programmes de r\u00e9mun\u00e9ration.<\/p>\n<p>L\u2019Ontario proc\u00e8de actuellement \u00e0 la mise en \u0153uvre d\u2019un nouveau cadre de r\u00e9mun\u00e9ration des cadres sup\u00e9rieurs du secteur parapublic, qui comprend l\u2019\u00e9tablissement d\u2019un plafond salarial ainsi que d\u2019un syst\u00e8me de r\u00e9mun\u00e9ration au rendement pour les h\u00f4pitaux, les coll\u00e8ges et universit\u00e9s, et d\u2019autres organismes gouvernementaux.<\/p>\n<p>Le Palais des congr\u00e8s du Toronto m\u00e9tropolitain (PCTM) a publi\u00e9 un document sur ce cadre de r\u00e9mun\u00e9ration (disponible ci-dessous). Il s\u2019agit d\u2019une exigence de la loi qui donne au public trente jours pour formuler des commentaires sur la fa\u00e7on dont le PCTM \u00e9tablit les salaires et avantages sociaux de ses cadres sup\u00e9rieurs. Le public est invit\u00e9 \u00e0 examiner cette \u00e9bauche de document et \u00e0 partager ses r\u00e9flexions d\u2019ici le 24 f\u00e9vrier 2018.<\/p>\n<p>Veuillez faire parvenir toute demande d\u2019information \u00e0 Marna Santo, vice-pr\u00e9sidente des ressources humaines, \u00e0\u00a0<a href=\"mailto:msanto@mtccc.com\">msanto@mtccc.com<\/a>.<\/p>\n<p><a class=\"acf-btn acf-btn-outline acf-header-btn pink-text\" href=\"\/wp-content\/uploads\/sites\/4\/2016\/11\/MTCC_BPSEC_final_FR.pdf\" target=\"_blank\">Consultez le cadre de r\u00e9mun\u00e9ration des cadres sup\u00e9rieurs du PCTM<\/a><\/p>\n<form id=\"aspnetForm\" action=\"\/corporate\/memorandumOfUnderstanding.aspx\" method=\"post\" name=\"aspnetForm\">\n<div id=\"ctl00_ctl00_baseContent_rightColContent_contnetControl_cmsContent\"><\/div>\n<\/form>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<em>Veuillez noter que vous aurez besoin d\u2019Acrobat Reader pour visualiser ce document.<\/em>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row disable_element=\u00a0\u00bbyes\u00a0\u00bb][vc_column][vc_column_text]La cr\u00e9ation du Palais des congr\u00e8s du Toronto m\u00e9tropolitain est le fruit d\u2019un travail collectif entre le gouvernement f\u00e9d\u00e9ral du Canada, la province de l\u2019Ontario et la municipalit\u00e9 de la r\u00e9gion m\u00e9tropolitaine de Toronto. Le MTCC est conforme aux exigences du gouvernement et est tenu pleinement responsable du strict respect de celles-ci.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text] Donn\u00e9es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":331759,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"page-fullwidth.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10131","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gouvernement ouvert - Metro Toronto Convention Centre<\/title>\n<meta name=\"description\" content=\"Learn about the MTCC\u2019s Corporate background, including Corporate Mandate, here.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gouvernement ouvert - Metro Toronto Convention Centre\" \/>\n<meta property=\"og:description\" content=\"Learn about the MTCC\u2019s Corporate background, including Corporate Mandate, here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/\" \/>\n<meta property=\"og:site_name\" content=\"Metro Toronto Convention Centre\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-25T18:59:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/open-government\\\/\",\"url\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/open-government\\\/\",\"name\":\"Gouvernement ouvert - Metro Toronto Convention Centre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/#website\"},\"datePublished\":\"2016-11-03T16:03:15+00:00\",\"dateModified\":\"2022-08-25T18:59:03+00:00\",\"description\":\"Learn about the MTCC\u2019s Corporate background, including Corporate Mandate, here.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/open-government\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/open-government\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/open-government\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entreprise\",\"item\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/corporate\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gouvernement ouvert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/\",\"name\":\"Metro Toronto Convention Centre\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev2.mtccc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gouvernement ouvert - Metro Toronto Convention Centre","description":"Learn about the MTCC\u2019s Corporate background, including Corporate Mandate, here.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/","og_locale":"fr_CA","og_type":"article","og_title":"Gouvernement ouvert - Metro Toronto Convention Centre","og_description":"Learn about the MTCC\u2019s Corporate background, including Corporate Mandate, here.","og_url":"https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/","og_site_name":"Metro Toronto Convention Centre","article_modified_time":"2022-08-25T18:59:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/","url":"https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/","name":"Gouvernement ouvert - Metro Toronto Convention Centre","isPartOf":{"@id":"https:\/\/dev2.mtccc.com\/fr\/#website"},"datePublished":"2016-11-03T16:03:15+00:00","dateModified":"2022-08-25T18:59:03+00:00","description":"Learn about the MTCC\u2019s Corporate background, including Corporate Mandate, here.","breadcrumb":{"@id":"https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev2.mtccc.com\/fr\/corporate\/open-government\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dev2.mtccc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Entreprise","item":"https:\/\/dev2.mtccc.com\/fr\/corporate\/"},{"@type":"ListItem","position":3,"name":"Gouvernement ouvert"}]},{"@type":"WebSite","@id":"https:\/\/dev2.mtccc.com\/fr\/#website","url":"https:\/\/dev2.mtccc.com\/fr\/","name":"Metro Toronto Convention Centre","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev2.mtccc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages\/10131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/comments?post=10131"}],"version-history":[{"count":14,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages\/10131\/revisions"}],"predecessor-version":[{"id":332530,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages\/10131\/revisions\/332530"}],"up":[{"embeddable":true,"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/pages\/331759"}],"wp:attachment":[{"href":"https:\/\/dev2.mtccc.com\/fr\/wp-json\/wp\/v2\/media?parent=10131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}